{"id":15852,"count":1,"description":"","link":"https:\/\/www.funminews.com\/index.php\/tag\/african-longest-serving-leaders\/","name":"African longest serving leaders","slug":"african-longest-serving-leaders","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/tags\/15852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/posts?tags=15852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}