{"id":15864,"count":1,"description":"","link":"https:\/\/www.funminews.com\/index.php\/tag\/museveni-son-muhoozi-succession\/","name":"Museveni son Muhoozi succession","slug":"museveni-son-muhoozi-succession","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/tags\/15864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.funminews.com\/index.php\/wp-json\/wp\/v2\/posts?tags=15864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}